{"id":1054,"date":"2022-05-12T01:10:21","date_gmt":"2022-05-12T01:10:21","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=1054"},"modified":"2022-05-12T01:10:25","modified_gmt":"2022-05-12T01:10:25","slug":"san-felipe-carabineros-inicia-proceso-de-admision-para-tecnicos-en-trabajo-social","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2022\/05\/12\/san-felipe-carabineros-inicia-proceso-de-admision-para-tecnicos-en-trabajo-social\/","title":{"rendered":"San Felipe: Carabineros Inicia Proceso De Admisi\u00f3n Para T\u00e9cnicos En Trabajo Social"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><em>Las inscripciones est\u00e1n abiertas en la Oficina de postulaciones Aconcagua de Carabineros hasta el viernes 27 de mayo.<\/em><\/p>\n\n\n\n<p>La&nbsp;<strong>Oficina de Postulaciones de la Prefectura Aconcagua de Carabineros<\/strong>&nbsp;anunci\u00f3 el inicio de un<strong>&nbsp;proceso de admisi\u00f3n para reclutar t\u00e9cnicos de nivel medio y superior en Trabajo Social<\/strong>, el que se encontrar\u00e1 abierto hasta el pr\u00f3ximo viernes 27 de mayo.<\/p>\n\n\n\n<p>Los interesados deben concurrir a la oficina de admisi\u00f3n, ubicada al interior del&nbsp;<strong>nuevo edificio de Carabineros en O\u00b4Higgins #200, San Felipe<\/strong>, donde deber\u00e1n acreditar requisitos como poseer el t\u00edtulo t\u00e9cnico profesional respectivo, nacionalidad chilena, tener entre 18 y 34 a\u00f1os de edad, entre otros que se detallar\u00e1n al momento de la postulaci\u00f3n.<\/p>\n\n\n\n<p>Finalizada la etapa de selecci\u00f3n, los postulantes que resulten seleccionados, deber\u00e1n realizar un curso de formaci\u00f3n de dos semestres acad\u00e9micos -en Santiago-, con inicio de clases el segundo semestre del a\u00f1o 2022, en modalidad de externado.<\/p>\n\n\n\n<p>Al momento de egresar de la etapa formativa, los oponentes ser\u00e1n nombrados en la planta de&nbsp;<strong>Carabineros de Chile<\/strong>, como Personal de Nombramiento Institucional (P.N.I.), del Escalaf\u00f3n de Apoyo Log\u00edstico \u2013 Asistente de Oficina para Apoyo Social y ser\u00e1n destinados a su primer lugar de trabajo, el que puede ser en cualquier lugar del territorio nacional.<\/p>\n\n\n\n<p>En tanto, conforme al prospecto de requisitos -que se encuentra publicado en la cuenta de&nbsp;<strong>Instagram<\/strong>&nbsp;<a href=\"http:\/\/instagram.com\/esfocar_oficial\/?hl=es\" target=\"_blank\" rel=\"noreferrer noopener\">@esfocar_oficial<\/a>-, el objetivo del cargo consiste principalmente en contribuir en la atenci\u00f3n preliminar de los requerimientos de intervenci\u00f3n social que requiera el personal y su grupo familiar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las inscripciones est\u00e1n abiertas en la Oficina de postulaciones Aconcagua de Carabineros hasta el viernes 27 de mayo. La&nbsp;Oficina de Postulaciones de la Prefectura Aconcagua de Carabineros&nbsp;anunci\u00f3 el inicio de un&nbsp;proceso de admisi\u00f3n para reclutar t\u00e9cnicos de nivel medio y superior en Trabajo Social, el que se encontrar\u00e1 abierto hasta el pr\u00f3ximo viernes 27 de &hellip;<\/p>\n","protected":false},"author":2,"featured_media":1055,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[7],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2022\/05\/Carabineros-postulacion-asistente-oficina-trabajo-social.jpg","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/1054"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=1054"}],"version-history":[{"count":1,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/1054\/revisions"}],"predecessor-version":[{"id":1056,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/1054\/revisions\/1056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/1055"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=1054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=1054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=1054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}