{"id":1165,"date":"2022-05-26T01:48:00","date_gmt":"2022-05-26T01:48:00","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=1165"},"modified":"2022-05-26T01:48:04","modified_gmt":"2022-05-26T01:48:04","slug":"veterinaria-municipal-informa-acerca-de-los-beneficios-de-la-esterilizacion-en-mascotas","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2022\/05\/26\/veterinaria-municipal-informa-acerca-de-los-beneficios-de-la-esterilizacion-en-mascotas\/","title":{"rendered":"Veterinaria Municipal informa acerca de los beneficios de la esterilizaci\u00f3n en mascotas"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><em>Desde el Centro de Atenci\u00f3n Primaria Animal de Los Andes, se hizo un llamado a la comunidad a informarse acerca de los beneficios de la esterilizaci\u00f3n de nuestras mascotas, al mismo tiempo que se realiz\u00f3 la invitaci\u00f3n a ponerse en contacto con su equipo, para as\u00ed obtener asesor\u00eda profesional.<\/em><\/p>\n\n\n\n<p>El procedimiento conocido como esterilizaci\u00f3n consiste en la extirpaci\u00f3n quir\u00fargica de ovarios y \u00fatero en hembras y test\u00edculos en caso de machos, con el fin de evitar la reproducci\u00f3n, suprimir el celo en hembras y evitar conductas indeseadas como marcaje y peleas, adem\u00e1s de cuidar la salud de perros y gatos, disminuyendo la posibilidad de tumores mamarios.<\/p>\n\n\n\n<p>Catalina Contreras, m\u00e9dico veterinario del equipo, detall\u00f3: \u201cSon m\u00faltiples los beneficios asociados a la esterilizaci\u00f3n. Evita camadas no deseadas que m\u00e1s tarde se convierten en animales abandonados, previene algunas enfermedades del tracto reproductivo como infecciones uterinas (metritis, piometras), c\u00e1ncer (mama, test\u00edculos), adem\u00e1s de situaciones que generan molestias para la comunidad como jaur\u00edas de perros en la v\u00eda p\u00fablica y accidentes de tr\u00e1nsito entre otras\u201d.<\/p>\n\n\n\n<p>Respecto a las condiciones pre y post operatorias, la profesional mencion\u00f3 que un animal cl\u00ednicamente sano puede ser esterilizado\/ castrado desde los 4 meses de vida, antes de su primer celo o antes de su primera camada. Por otro lado, se recomienda a los due\u00f1os preparar un sitio c\u00f3modo y limpio para su recuperaci\u00f3n en casa, evitar el lamido en la zona de la herida y la remoci\u00f3n de las suturas, constante limpieza, desinfecci\u00f3n y protecci\u00f3n de la herida, y el correcto suministro de los medicamentos que el profesional indique.<\/p>\n\n\n\n<p>Finalmente, Contreras, agreg\u00f3: \u201cTodos quienes necesiten asesor\u00eda profesional se pueden inscribir y ac\u00e1 los citaremos a una hora determinada para ayudarlos con dicha intervenci\u00f3n\u201d.<\/p>\n\n\n\n<p>De esta manera, extendemos la invitaci\u00f3n a obtener mayor informaci\u00f3n respecto a este tipo de procedimientos, llamando al 342507825 o acerc\u00e1ndose presencialmente a las dependencias de la Veterinaria, ubicadas en Salvador Allende 131, en horario de 8:30 a 17:00.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el Centro de Atenci\u00f3n Primaria Animal de Los Andes, se hizo un llamado a la comunidad a informarse acerca de los beneficios de la esterilizaci\u00f3n de nuestras mascotas, al mismo tiempo que se realiz\u00f3 la invitaci\u00f3n a ponerse en contacto con su equipo, para as\u00ed obtener asesor\u00eda profesional. El procedimiento conocido como esterilizaci\u00f3n consiste &hellip;<\/p>\n","protected":false},"author":2,"featured_media":1166,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[7],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2022\/05\/ESTERELIZACION.jpg","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/1165"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=1165"}],"version-history":[{"count":1,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/1165\/revisions"}],"predecessor-version":[{"id":1167,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/1165\/revisions\/1167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/1166"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=1165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=1165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=1165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}