{"id":1223,"date":"2022-06-03T22:28:42","date_gmt":"2022-06-03T22:28:42","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=1223"},"modified":"2022-06-03T22:28:45","modified_gmt":"2022-06-03T22:28:45","slug":"en-los-andes-el-mes-del-medio-ambiente-se-celebra-con-varias-acciones-sustentables","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2022\/06\/03\/en-los-andes-el-mes-del-medio-ambiente-se-celebra-con-varias-acciones-sustentables\/","title":{"rendered":"En Los Andes, el mes del medio ambiente se celebra con varias acciones sustentables"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><em>El domingo 05 de junio es el d\u00eda del medio ambiente, y el municipio andino a trav\u00e9s de la subdirecci\u00f3n de Sustentabilidad, ha preparado durante todo el mes varias actividades que incentivan el cuidado al planeta.<\/em><\/p>\n\n\n\n<p>Con un operativo de limpieza en la poblaci\u00f3n Bellavista 1 y 2, la subdirecci\u00f3n de Sustentabilidad dio el vamos al mes del medio ambiente. En conjunto a Cosemar y el apoyo de los vecinos y Carabineros, se realiz\u00f3 esta actividad de limpieza en el sector aleda\u00f1o a la carretera, con la idea de fomentar mejores entornos, erradicando microbasurales que se generan por la propia acci\u00f3n humana.<\/p>\n\n\n\n<p>Lo anterior, a prop\u00f3sito que el municipio celebrar\u00e1 el mes del ambiente, pues el 05 de junio es la efem\u00e9ride a nivel internacional, cuyo lema para este a\u00f1o es \u201cUna sola Tierra\u201d, acogido por el Programa de las Naciones Unidas para el medio ambiente.<\/p>\n\n\n\n<p>Marlene V\u00e1squez, subdirectora de Sustentabilidad coment\u00f3 que \u201cseguimos trabajando por mejorar los espacios de Los Andes, dando inicio al mes del medio ambiente con este operativo con el que quisimos involucrar a los vecinos para conversar limpio este espacio, tambi\u00e9n sirve de recreaci\u00f3n y brinda un mejor entorno, al evitarse la contaminaci\u00f3n\u201d.<\/p>\n\n\n\n<p>En este sentido, M\u00f3nica Chac\u00f3n, presidenta de la Junta de Vecinos de la poblaci\u00f3n Bellavista I, dijo que encontraba s\u00faper bueno lo que se est\u00e1 haciendo y que lamenta que los vecinos no cuidan su entorno.<\/p>\n\n\n\n<p>El programa contempla, adem\u00e1s para el lunes 06 operativo de reciclaje con vecinos de las cuatro Villas, lunes 13 y mi\u00e9rcoles 15 de junio se har\u00e1n charlas medioambientales en el Punto Verde para alumnos de 3\u00b0 y 4\u00b0 b\u00e1sico; mi\u00e9rcoles 22 una muestra de las tres subdirecciones de la direcci\u00f3n de Medio Ambiente, y el mi\u00e9rcoles 29 de junio el lanzamiento de los puntos limpios en establecimientos educacionales.<\/p>\n\n\n\n<p>Cristian Veloso, director de Medio Ambiente, dijo que \u201cadem\u00e1s se involucrar\u00e1 el Centro de Atenci\u00f3n Primaria Animal, con la realizaci\u00f3n de operativos de vacunaci\u00f3n y desparasitaci\u00f3n de animales, mientras que la subdirecci\u00f3n de Aseo y Ornato, har\u00e1 sociabilizaci\u00f3n sobre el buen manejo de la poda, arbolado, manejo de residuos, y el cuidado de las \u00e1reas verdes\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El domingo 05 de junio es el d\u00eda del medio ambiente, y el municipio andino a trav\u00e9s de la subdirecci\u00f3n de Sustentabilidad, ha preparado durante todo el mes varias actividades que incentivan el cuidado al planeta. Con un operativo de limpieza en la poblaci\u00f3n Bellavista 1 y 2, la subdirecci\u00f3n de Sustentabilidad dio el vamos &hellip;<\/p>\n","protected":false},"author":2,"featured_media":1224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[7],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2022\/06\/MEDIO-AMBIENTE.jpeg","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/1223"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=1223"}],"version-history":[{"count":1,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/1223\/revisions"}],"predecessor-version":[{"id":1225,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/1223\/revisions\/1225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/1224"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=1223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=1223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=1223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}