{"id":1360,"date":"2022-07-14T00:30:46","date_gmt":"2022-07-14T00:30:46","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=1360"},"modified":"2022-07-14T00:30:49","modified_gmt":"2022-07-14T00:30:49","slug":"equipos-municipales-de-san-esteban-trabajaron-intensamente-para-ir-en-apoyo-de-los-vecinos-durante-el-paso-del-sistema-frontal","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2022\/07\/14\/equipos-municipales-de-san-esteban-trabajaron-intensamente-para-ir-en-apoyo-de-los-vecinos-durante-el-paso-del-sistema-frontal\/","title":{"rendered":"Equipos Municipales de San Esteban trabajaron intensamente para ir en apoyo de los vecinos durante el paso del sistema frontal"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<ul><li>No hubo emergencias complejas en la comuna, salvo la complicaci\u00f3n de cerca de 50 veh\u00edculos para descender desde Campos de Ahumada, pese a los llamados de las autoridades a no asistir a la precordillera por la gran cantidad de nieve ca\u00edda<a><\/a>.<\/li><\/ul>\n\n\n\n<p>Durante el fin de semana, los equipos municipales de San Esteban estuvieron desplegados en todo el territorio para solucionar las contingencias provocadas por el paso del sistema frontal por la comuna, lo que, afortunadamente, no se tradujo en graves emergencias.<\/p>\n\n\n\n<p>En las \u00faltimas horas, el Administrador Municipal, Ra\u00fal Iduarte, junto al Director de Emergencias, Carlos \u00c1lamos, realizaron gestiones que permitan quitar la nieve de aquellas rutas precordilleranas que se encuentran intransitables.<\/p>\n\n\n\n<p>\u201cLa comuna recibi\u00f3 intensas nevadas en pre cordillera, afectando sectores afectados con deslizamiento de rocas y socavamientos. En San Francisco y Campos de Ahumada est\u00e1n las situaciones m\u00e1s complejas, donde tenemos nevadas sobre los 30 y 40 cent\u00edmetros en algunos puntos, lo cual impide el desplazamiento\u201d, sostuvo \u00c1lamos.<\/p>\n\n\n\n<p>Por este motivo, el municipio en conjunto con los vecinos, Carabineros y Vialidad, decidieron cerrar la ruta de acceso, a la altura de la Escuela de Campos de Ahumada, la que quedar\u00e1 habilitada s\u00f3lo para residentes. A esta determinaci\u00f3n se sum\u00f3 la emergencia acontecida durante la tarde del domingo, cuando cerca de 50 veh\u00edculos presentaron problemas para descender desde estas zonas, lo que fue solucionado en un trabajo conjunto entre equipos municipales de emergencia, bomberos, carabineros y jeeperos.&nbsp;<\/p>\n\n\n\n<p>\u201cReiteramos&nbsp; y somos enf\u00e1ticos en que la comunidad no asista a campos de ahumada ni a zonas precordilleranas a hacer turismo ni paseos. Es tiempo de quedarse en casa, y evitar situaciones de emergencia\u201d, sostuvo Ra\u00fal Iduarte.<\/p>\n\n\n\n<p>El mismo llamado realiz\u00f3, a trav\u00e9s de las redes sociales del municipio, el Alcalde Ortega, durante la ma\u00f1ana del pasado domingo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No hubo emergencias complejas en la comuna, salvo la complicaci\u00f3n de cerca de 50 veh\u00edculos para descender desde Campos de Ahumada, pese a los llamados de las autoridades a no asistir a la precordillera por la gran cantidad de nieve ca\u00edda. Durante el fin de semana, los equipos municipales de San Esteban estuvieron desplegados en &hellip;<\/p>\n","protected":false},"author":2,"featured_media":1361,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[2],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2022\/07\/CIERRE-CAMINO-CAMPOS-DE-AHUMADA.jpeg","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/1360"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=1360"}],"version-history":[{"count":1,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/1360\/revisions"}],"predecessor-version":[{"id":1362,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/1360\/revisions\/1362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/1361"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=1360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=1360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=1360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}