{"id":1399,"date":"2022-07-21T02:14:48","date_gmt":"2022-07-21T02:14:48","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=1399"},"modified":"2022-07-21T02:14:51","modified_gmt":"2022-07-21T02:14:51","slug":"departamento-de-salud-de-san-esteban-invito-a-vecinas-a-realizarse-gratuitamente-el-papanicolau","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2022\/07\/21\/departamento-de-salud-de-san-esteban-invito-a-vecinas-a-realizarse-gratuitamente-el-papanicolau\/","title":{"rendered":"Departamento de Salud de San Esteban invit\u00f3 a vecinas a realizarse gratuitamente el Papanicolau"},"content":{"rendered":"\n<p><em>El Cesfam abri\u00f3 una agenda exclusiva para la toma del examen.<\/em><\/p>\n\n\n\n<p>Desde el Departamento de Salud de San Esteban, realizaron un llamado a las mujeres de la comuna que no tengan su examen Papanicolau vigente en los \u00faltimos tres a\u00f1os a realizarlo gratuitamente en el Cesfam de la comuna, para prevenir el c\u00e1ncer de cuello uterino, que en Chile es el tercer tipo de c\u00e1ncer m\u00e1s frecuente y el sexto en mortalidad.<\/p>\n\n\n\n<p>El Papanicolau o m\u00e1s conocido como \u00a8PAP\u00a8 es un examen que se realiza a las mujeres de entre 25 y 64 a\u00f1os (Idealmente), para ayudar a prevenir y detectar temprano el c\u00e1ncer de cuello uterino. Aun as\u00ed, la matrona Elizabeth M\u00e1rquez del Cesfam de San Esteban, aclar\u00f3 que hay excepciones a ese rango de edad cuando lo amerite.<\/p>\n\n\n\n<p>Dentro de la estrategia para incentivar la toma de PAP en las mujeres de la comuna, se tom\u00f3 la medida de realizar una extensi\u00f3n horaria con agenda exclusiva para realizar la prestaci\u00f3n, permitiendo que las usuarias que no tienen acceso durante los horarios en que funciona el establecimiento, tambi\u00e9n puedan poner al d\u00eda su examen.<\/p>\n\n\n\n<p>\u201cSe decide realizar extensi\u00f3n horaria debido a que muchas de las usuarias que pertenecen al Cesfam no pod\u00edan asistir en el horario habitual de 8:00 a 17:00 hrs, lo cual complica bastante el acceso a la realizaci\u00f3n del examen. Es por ello que realizamos un llamado a todas las vecinas de la comuna de San Esteban a que se acerquen al establecimiento de salud seg\u00fan corresponda, ya sea Cecosf, postas rurales o Cesfam y soliciten hora para toma de PAP con matr\u00f3n o matrona\u201d, coment\u00f3 Elizabeth M\u00e1rquez, matrona del Cesfam de la comuna.<\/p>\n\n\n\n<p>Adem\u00e1s, la matrona destac\u00f3 que tambi\u00e9n hace un llamado a las mujeres que ya est\u00e1n en seguimiento y necesitan realizarse el examen anualmente que lo hagan, ya que son personas de alto riesgo ante el c\u00e1ncer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Cesfam abri\u00f3 una agenda exclusiva para la toma del examen. Desde el Departamento de Salud de San Esteban, realizaron un llamado a las mujeres de la comuna que no tengan su examen Papanicolau vigente en los \u00faltimos tres a\u00f1os a realizarlo gratuitamente en el Cesfam de la comuna, para prevenir el c\u00e1ncer de cuello &hellip;<\/p>\n","protected":false},"author":2,"featured_media":1400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[2],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2022\/07\/ESPECULO-EXAMEN-DE-PAPANICOLAU-scaled.jpg","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/1399"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=1399"}],"version-history":[{"count":1,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/1399\/revisions"}],"predecessor-version":[{"id":1401,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/1399\/revisions\/1401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/1400"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=1399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=1399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=1399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}