{"id":2637,"date":"2023-02-02T23:51:08","date_gmt":"2023-02-02T23:51:08","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=2637"},"modified":"2023-02-02T23:59:07","modified_gmt":"2023-02-02T23:59:07","slug":"esval-ola-de-calor-haria-aumentar-en-hasta-un-9","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2023\/02\/02\/esval-ola-de-calor-haria-aumentar-en-hasta-un-9\/","title":{"rendered":"Esval: ola de calor har\u00eda aumentar en hasta un 9%"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<ul><li><em><\/em><\/li><\/ul>\n\n\n\n<p><strong>Valpara\u00edso,  febrero 2023.- <\/strong>La Direcci\u00f3n Meteorol\u00f3gica de Chile (DMC) emiti\u00f3 una alerta debido a la llegada de una nueva ola de calor a partir de este jueves, que se extender\u00e1 por gran parte de la zona central del pa\u00eds. En el caso de la Regi\u00f3n de Valpara\u00edso, se prev\u00e9 que, en sectores como el Valle de Aconcagua, las temperaturas bordear\u00e1n los 40 grados, generando un importante aumento en el consumo de agua potable.<\/p>\n\n\n\n<p>\u201cEn base a nuestra experiencia con eventos anteriores de este tipo, vemos que con el aumento de la temperatura promedio en alrededor de 10\u00b0C, el consumo del recurso h\u00eddrico tambi\u00e9n se incrementa, en cerca de un 9%. Esto implica que nuestros sistemas deben producir m\u00e1s de 300 litros por segundo adicionales a los de un d\u00eda normal, para cubrir adecuadamente la demanda de los usuarios\u201d, detall\u00f3 el gerente regional de Esval, Alejandro Salas.<\/p>\n\n\n\n<p>El ejecutivo agreg\u00f3 que, como se\u00f1alan los especialistas, estos peaks de temperatura son cada vez m\u00e1s frecuentes, producto de los efectos del cambio clim\u00e1tico. \u201cLa sequ\u00eda sigue siendo profunda en la regi\u00f3n, por lo tanto, hacer el uso m\u00e1s eficiente posible del recurso es fundamental. Gracias a las lluvias del pasado invierno y a la acumulaci\u00f3n que de estas realizamos principalmente en el embalse Los Aromos -gracias a nuestra conducci\u00f3n reversible- hoy podemos sostener la actual demanda, pero continuamos lejos de una situaci\u00f3n normal\u201d, record\u00f3.<\/p>\n\n\n\n<p>Seg\u00fan el balance h\u00eddrico de Esval, la temporada 2022 finaliz\u00f3 con un d\u00e9ficit de agua ca\u00edda del 49% en San Felipe, mientras que, en localidades como Petorca o San Antonio, la disminuci\u00f3n de lluvias super\u00f3 el 35%, en relaci\u00f3n con un a\u00f1o normal. En tanto, la acumulaci\u00f3n de nieve en la cordillera registr\u00f3 un d\u00e9ficit del 97%, respecto del promedio hist\u00f3rico.<\/p>\n\n\n\n<p>\u201cHemos desplegado todos nuestros esfuerzos para realizar las inversiones necesarias que nos permitan mantener la continuidad del suministro durante toda la temporada estival y adelantarnos a los pr\u00f3ximos meses, pero ese trabajo queda incompleto sin un compromiso de todos con el consumo responsable\u201d, agreg\u00f3 Salas.<\/p>\n\n\n\n<p><strong>Consejos para seguir en casa<\/strong><\/p>\n\n\n\n<p>Si bien en estas fechas la hidrataci\u00f3n es fundamental y el llamado es a beber al menos 2 litros de agua al d\u00eda, existen otras acciones que podemos realizar en nuestros hogares para tener un uso m\u00e1s eficiente del recurso h\u00eddrico:<\/p>\n\n\n\n<ul><li>Evite regar entre las 10:00 y las 20:00 horas (para prevenir la evaporaci\u00f3n por el calor) y reutilice el agua de cocci\u00f3n y remojo para regar las plantas.<\/li><li>Cierre la llave del agua mientras se cepilla los dientes o se afeita. De esta manera ahorrar\u00e1 unos 12 litros de agua por minuto.<\/li><li>Grad\u00fae la apertura de la llave a lo que necesita, abrirla completamente es innecesario.<\/li><li>Tome duchas breves y cierre la llave mientras se jabona o aplica champ\u00fa. Ahorrar\u00e1 120 litros en promedio cada vez.<\/li><li>Limpie los filtros de su grifer\u00eda una vez al a\u00f1o.<\/li><li>Arregle todas las llaves que goteen, puede ahorrarse hasta 180 litros.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Valpara\u00edso, febrero 2023.- La Direcci\u00f3n Meteorol\u00f3gica de Chile (DMC) emiti\u00f3 una alerta debido a la llegada de una nueva ola de calor a partir de este jueves, que se extender\u00e1 por gran parte de la zona central del pa\u00eds. En el caso de la Regi\u00f3n de Valpara\u00edso, se prev\u00e9 que, en sectores como el Valle &hellip;<\/p>\n","protected":false},"author":2,"featured_media":2638,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[3],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2023\/02\/Ola-de-calor-V-Region.jpeg","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/2637"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2637"}],"version-history":[{"count":2,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/2637\/revisions"}],"predecessor-version":[{"id":2641,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/2637\/revisions\/2641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/2638"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}