{"id":3623,"date":"2023-09-13T00:26:27","date_gmt":"2023-09-13T00:26:27","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=3623"},"modified":"2023-09-13T00:26:29","modified_gmt":"2023-09-13T00:26:29","slug":"municipio-de-san-esteban-y-su-departamento-de-salud-firmaron-compromiso-por-una-comuna-mas-saludable","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2023\/09\/13\/municipio-de-san-esteban-y-su-departamento-de-salud-firmaron-compromiso-por-una-comuna-mas-saludable\/","title":{"rendered":"Municipio de San Esteban y su Departamento de Salud firmaron compromiso por una comuna m\u00e1s saludable"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<ul><li>Durante esta ceremonia, que se desarroll\u00f3 para culminar la Semana de la Atenci\u00f3n Primaria, tambi\u00e9n se reconoci\u00f3 a funcionarios por sus a\u00f1os de trayectoria.<\/li><\/ul>\n\n\n\n<p>Con el fin de continuar promoviendo la salud entre las vecinas y vecinos de San Esteban y fortalecer el compromiso de la actual administraci\u00f3n con la prevenci\u00f3n de enfermedades a trav\u00e9s de su Departamento de Salud, es que las autoridades, encabezadas por el alcalde Christian Ortega y el administrador municipal, Ra\u00fal Iduarte, firmaron de forma tangible un compromiso por hacer de San Esteban una comuna m\u00e1s saludable.<\/p>\n\n\n\n<p>Este acuerdo, en el que tambi\u00e9n estamparon sus firmas los directores del departamento de salud, Juan Antonio Lobos y Felipe Cid, director del cesfam de la comuna, significa un paso importante respecto al fortalecimiento del rol del municipio como actor relevante y agente de cambio en la creaci\u00f3n de pol\u00edticas que vayan en pos de la salud de la comunidad<\/p>\n\n\n\n<p>\u201cEsta historia (De la atenci\u00f3n Primaria de Salud), cierto, que se ha construido en todos estos a\u00f1os, nos da pie para que hoy nuestra comuna, m\u00e1s que nunca, tome un compromiso. El d\u00eda de hoy han firmado nuestro alcalde, el administrador, yo y el director del Cesfam junto a los funcionarios con la comunidad de San Esteban, para comprometernos como dije, a ser una comuna saludable y comprometida con el desarrollo y bienestar de la comuna y de alguna forma, retribuir el cari\u00f1o que la gente nos entrega cada d\u00eda y poder fortalecer este v\u00ednculo que necesitamos y tenemos con cada uno de nuestros usuarios a lo largo del ciclo vital. Esperamos que la conmemoraci\u00f3n que hemos realizado refuerce este v\u00ednculo, este compromiso y estemos a la altura de los desaf\u00edos que la comuna nos plantea y principalmente prepar\u00e1ndonos para el cambio de casa en nuestro nuevo edificio, en el primer trimestre del a\u00f1o 2024, donde esperamos ya estar inaugurando junto a nuestro alcalde y toda la comunidad\u201d, agreg\u00f3 el director del Departamento de Salud municipal, Juan Antonio Lobos.<\/p>\n\n\n\n<p>Cabe destacar que la firma de este documento se enmarca en la incorporaci\u00f3n de San Esteban al movimiento de Municipios, Ciudades y Comunidades Saludables de Chile, de la comisi\u00f3n de salud de la Asociaci\u00f3n Chilena de Municipalidades, transformando a la comuna en una de las 16 pioneras a nivel nacional en pertenecer a esta alianza.<\/p>\n\n\n\n<p><strong>Reconocimiento a funcionarios por a\u00f1os de servicio<\/strong><\/p>\n\n\n\n<p>Adem\u00e1s, en la ceremonia se reconoci\u00f3 a los funcionarios que han tenido una reconocida trayectoria en los diferentes dispositivos de salud de la comuna, destacando a quienes cumplen 5, 10 y 15 a\u00f1os trabajando por la salud de la comunidad. Tambi\u00e9n, se reconoci\u00f3 a la T\u00e9cnico en Enfermer\u00eda M\u00f3nica Ram\u00edrez, quien lleva 35 a\u00f1os en el Departamento de Salud de San Esteban, espec\u00edficamente en el Cecosf de Lo Calvo, realizando una labor impecable.<\/p>\n\n\n\n<p>\u201cLa verdad es que como lo dije, en la palabra a los funcionarios, estamos muy contentos y orgullos de que el trabajo que hacen y tambi\u00e9n lo que significa la atenci\u00f3n primaria de salud para los habitantes de San Esteban, un servicio que se brinda en todo el territorio, as\u00ed que nada m\u00e1s que felicitarlos, agradecerles y tambi\u00e9n comprometerlos poque se nos viene un nuevo desaf\u00edo que es el Cesfam, donde las expectativas son muy altas de nuestra comunidad y necesitamos un equipo bien cohesionado y bien comprometido\u201d, coment\u00f3 el alcalde Christian Ortega Villagras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante esta ceremonia, que se desarroll\u00f3 para culminar la Semana de la Atenci\u00f3n Primaria, tambi\u00e9n se reconoci\u00f3 a funcionarios por sus a\u00f1os de trayectoria. Con el fin de continuar promoviendo la salud entre las vecinas y vecinos de San Esteban y fortalecer el compromiso de la actual administraci\u00f3n con la prevenci\u00f3n de enfermedades a trav\u00e9s &hellip;<\/p>\n","protected":false},"author":2,"featured_media":3625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[2],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2023\/09\/FIRMA-SAN-ESTEBAN-SALUDABLE-1.jpeg","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/3623"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=3623"}],"version-history":[{"count":1,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/3623\/revisions"}],"predecessor-version":[{"id":3626,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/3623\/revisions\/3626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/3625"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=3623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=3623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=3623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}