{"id":3650,"date":"2023-09-29T01:06:46","date_gmt":"2023-09-29T01:06:46","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=3650"},"modified":"2023-09-29T01:06:47","modified_gmt":"2023-09-29T01:06:47","slug":"usuarias-de-programa-jefas-de-hogar-de-san-esteban-participaron-en-interesante-taller-de-apicultura","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2023\/09\/29\/usuarias-de-programa-jefas-de-hogar-de-san-esteban-participaron-en-interesante-taller-de-apicultura\/","title":{"rendered":"Usuarias de programa jefas de hogar de San Esteban participaron en interesante taller de apicultura"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<ul><li>La exitosa iniciativa est\u00e1 enmarcada en un calendario de trabajo, que se ha visto robustecido con otras actividades, tales como la realizaci\u00f3n de un huerto sustentable.<\/li><\/ul>\n\n\n\n<p>El programa jefas de hogar de San Esteban contin\u00faa trabajando en distintas iniciativas que permitan promover la autonom\u00eda econ\u00f3mica de sus usuarias. En esta oportunidad, las coordinadoras en compa\u00f1\u00eda de un grupo de participantes, asistieron a un interesante taller de apicultura, desarrollado de manera conjunta entre el Centro de Educaci\u00f3n Ambiental (CEMAC) de la comuna y Apisweet home, en San Francisco.<\/p>\n\n\n\n<p>En la oportunidad, los instructores entregaron conocimientos b\u00e1sicos respecto a la disciplina, la labor del apicultor, el proceso de elaboraci\u00f3n de la miel, y el cuidado a las abejas.<\/p>\n\n\n\n<p>En ese sentido, Gabriela Gallardo, una de las coordinadora del programa de SernamEG, y ejecutado por el municipio sanestebino, agradeci\u00f3 el inter\u00e9s de las usuarias, as\u00ed como tambi\u00e9n el apoyo de Julio Figueroa (apisweet home) y Sebasti\u00e1n Ahumada (CEMAC) por apoyar y orientar el taller.<\/p>\n\n\n\n<p>\u201cEstamos muy contentos con la realizaci\u00f3n de este taller. Esta es una actividad dedicada a la crianza de las abejas, brind\u00e1ndole los cuidados necesarios, con el objetivo de obtener y consumir los productos que son capaces de elaborar y recolectar. As\u00ed, en un futuro, pueden comercializar la miel y sus derivados, como el polen, el propoleo, jalea real y la cera\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>Para la profesional \u201cesta fue una instancia sumamente enriquecedora para nuestras usuarias, ya que nos permite conocer y aportar en un \u00e1rea muy poco conocida y que es muy interesante\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>Este tipo de actividades se suman a las ya desarrolladas por el programa Jefas de Hogar, las cuales han dado positivos resultados, tales como la realizaci\u00f3n de un huerto sustentable, entre otras iniciativas.&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La exitosa iniciativa est\u00e1 enmarcada en un calendario de trabajo, que se ha visto robustecido con otras actividades, tales como la realizaci\u00f3n de un huerto sustentable. El programa jefas de hogar de San Esteban contin\u00faa trabajando en distintas iniciativas que permitan promover la autonom\u00eda econ\u00f3mica de sus usuarias. En esta oportunidad, las coordinadoras en compa\u00f1\u00eda &hellip;<\/p>\n","protected":false},"author":2,"featured_media":3651,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[2],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2023\/09\/apicultura-1.jpeg","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/3650"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=3650"}],"version-history":[{"count":1,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/3650\/revisions"}],"predecessor-version":[{"id":3652,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/3650\/revisions\/3652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/3651"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=3650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=3650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=3650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}