{"id":3653,"date":"2023-10-02T23:57:22","date_gmt":"2023-10-02T23:57:22","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=3653"},"modified":"2023-10-02T23:57:24","modified_gmt":"2023-10-02T23:57:24","slug":"mas-de-70-sanestebinas-se-realizaron-gratuitamente-la-mamografia-en-operativo-movil-de-la-fundacion-oncologica-arturo-lopez-perez","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2023\/10\/02\/mas-de-70-sanestebinas-se-realizaron-gratuitamente-la-mamografia-en-operativo-movil-de-la-fundacion-oncologica-arturo-lopez-perez\/","title":{"rendered":"M\u00e1s de 70 sanestebinas se realizaron gratuitamente la mamograf\u00eda en operativo m\u00f3vil de la Fundaci\u00f3n Oncol\u00f3gica Arturo L\u00f3pez P\u00e9rez"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<ul><li>El municipio, a trav\u00e9s de su Departamento de Salud, gestion\u00f3 la realizaci\u00f3n de estas atenciones<\/li><\/ul>\n\n\n\n<p>Durante dos d\u00edas, m\u00e1s de 70 mujeres de San Esteban se realizaron el examen de la mamograf\u00eda completamente gratis en la cl\u00ednica m\u00f3vil de la Fundaci\u00f3n Arturo L\u00f3pez P\u00e9rez que fue instalada en la Plaza de Armas de la comuna.<\/p>\n\n\n\n<p>El municipio, a trav\u00e9s de su Departamento de Salud, gestion\u00f3 la realizaci\u00f3n del operativo y su log\u00edstica, asimismo, apoy\u00f3 en la labor de agendar las horas de atenci\u00f3n, permitiendo con ello, que las vecinas fueran atendidas en su propia comuna, sin necesidad de trasladarse a otros puntos del valle.<\/p>\n\n\n\n<p>\u201cEstuvimos en la plaza de armas de San Esteban recibiendo con enorme alegr\u00eda la cl\u00ednica m\u00f3vil del instituto oncol\u00f3gico de Chile, FALP, con quienes hemos realizado un convenio que permiti\u00f3 la atenci\u00f3n de nuestras vecinas mayores de 35 a\u00f1os, sin necesidad de orden m\u00e9dica, durante los \u00faltimos dos d\u00edas,&nbsp; para de alguna forma marcar el inicio de lo que ser\u00e1 durante octubre, el mes del c\u00e1ncer de mama.\u201d, coment\u00f3 el director del Departamento de Salud Juan Antonio Lobos.<\/p>\n\n\n\n<p>Cabe destacar que esta prestaci\u00f3n gratuita se encuentra constantemente disponible para las mujeres mayores de 50 a\u00f1os que est\u00e1n inscritas en Fonasa, solo deben acercarse a solicitarla en los centros de salud de San Esteban.<\/p>\n\n\n\n<p>\u201cEste operativo hoy es a partir de los 35 a\u00f1os pero quiero recordar a la comunidad que nosotros como Cesfam San Esteban, contamos todos los a\u00f1os con m\u00e1s de mil cupos para poder hacer mamograf\u00edas entre los 50 y los69 a\u00f1os y es totalmente gratis, as\u00ed que los invito a poder acercarse al Cesfam a pedir informaci\u00f3n para poder acceder al examen de mamograf\u00eda orientado a la prevenci\u00f3n del c\u00e1ncer de mama\u201d, agreg\u00f3 Felipe Cid, director del Cesfam de San Esteban.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El municipio, a trav\u00e9s de su Departamento de Salud, gestion\u00f3 la realizaci\u00f3n de estas atenciones Durante dos d\u00edas, m\u00e1s de 70 mujeres de San Esteban se realizaron el examen de la mamograf\u00eda completamente gratis en la cl\u00ednica m\u00f3vil de la Fundaci\u00f3n Arturo L\u00f3pez P\u00e9rez que fue instalada en la Plaza de Armas de la comuna. &hellip;<\/p>\n","protected":false},"author":2,"featured_media":3654,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[2],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2023\/10\/OPERATIVO-MAMOGRAFI\u0301A-FALP-2.jpg","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/3653"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=3653"}],"version-history":[{"count":1,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/3653\/revisions"}],"predecessor-version":[{"id":3655,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/3653\/revisions\/3655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/3654"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=3653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=3653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=3653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}