{"id":3818,"date":"2023-12-05T03:04:05","date_gmt":"2023-12-05T03:04:05","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=3818"},"modified":"2023-12-05T03:04:07","modified_gmt":"2023-12-05T03:04:07","slug":"gobierno-regional-de-valparaiso-aprueba-importante-cartera-de-proyectos-por-mas-de-28-mil-millones-de-pesos-ademas-de-la-continuidad-hasta-marzo-de-programas-proempleo-en-la-region","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2023\/12\/05\/gobierno-regional-de-valparaiso-aprueba-importante-cartera-de-proyectos-por-mas-de-28-mil-millones-de-pesos-ademas-de-la-continuidad-hasta-marzo-de-programas-proempleo-en-la-region\/","title":{"rendered":"Gobierno Regional de Valpara\u00edso aprueba importante cartera de proyectos por m\u00e1s de 28 mil millones de pesos adem\u00e1s de la continuidad hasta marzo de programas proempleo en la regi\u00f3n"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><strong>&#8211; <\/strong>En pleno del Consejo Regional se aprob\u00f3 as\u00ed el financiamiento para 27 proyectos (FNDR) en la regi\u00f3n, en donde tambi\u00e9n destaca un aporte de m\u00e1s de 4 mil millones de pesos para nuevo centro Telet\u00f3n en Valpara\u00edso.<strong><\/strong><\/p>\n\n\n\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n\n\n\n<p>Una importante cartera de proyectos, priorizada por el Gobernador Regional Rodrigo Mundaca, fue aprobada en esta jornada por el pleno del Consejo Regional de Valpara\u00edso (CORE). En total, una inversi\u00f3n de $28.082.186.000 de pesos en distintos proyectos para la regi\u00f3n de Valpara\u00edso se votaron de forma favorable, destacando entre ellos $4.851.971.000 de pesos para la reposici\u00f3n del Centro de Rehabilitaci\u00f3n de Telet\u00f3n en Valpara\u00edso, y una inversi\u00f3n de $3.120.739.470 de pesos para la continuidad del programa proempleo (PIC2 y PIC 4) en la regi\u00f3n hasta marzo 2024.<\/p>\n\n\n\n<p>De esta forma, en la modalidad del Fondo Nacional de Desarrollo Regional (FNDR) se aprobaron 27 iniciativas en la regi\u00f3n por un monto total de $23.052.847.000 de pesos, en donde destacan la reposici\u00f3n de cuarteles de Bomberos en Rinconada (M$1.944.164), Los Andes (M$77.041), y Calle Larga (M$92.924), junto al mejoramiento de pavimentos en las comunas de Olmu\u00e9, Quilpu\u00e9 y Villa Alemana. Con ello tambi\u00e9n se financiaron importantes recursos para la ampliaci\u00f3n de red de alcantarillados en Petorca (M$1.996.023), la construcci\u00f3n de red de alcantarillados en La Ligua (M$3.125.048), la normalizaci\u00f3n colegio TP Mercedes Mataran en Zapallar (M$2.035.686), el mejoramiento de pavimentaci\u00f3n en AV. Ignacio Carrera de Cartagena (M$1.750.047), el mejoramiento circuito vial en El Tabo (M$1683.325), la construcci\u00f3n del cuartel de la primera Compa\u00f1\u00eda de Bomberos de Putaendo (M$213.394), la construcci\u00f3n de sede de Adulto Mayor en Santa Maria (M$828.668), la construcci\u00f3n del puente Ruperto Bernal en Puchuncav\u00ed (M$1.448.870), y la restauraci\u00f3n del Ascensor Lecheros en Valpara\u00edso (M$299.434), entre otros proyectos.<\/p>\n\n\n\n<p>Asimismo, se financiaron proyectos v\u00eda Circular 33 por un total de M$3.034.840 de pesos, entre los que se pueden resaltar la reposici\u00f3n de veh\u00edculos municipales de Calle Larga, equipos para voluntarios del Bote Salvavidas de Valpara\u00edso, reposici\u00f3n de dos ambulancias b\u00e1sicas para Papudo, adquisici\u00f3n de c\u00e1maras de televigilancia para Hijuelas, adquisici\u00f3n de contenedores de basura en Quillota, Adquisici\u00f3n oficina m\u00f3vil y camioneta de seguridad para Santo Domingo, adquisici\u00f3n de veh\u00edculo de acceso universal para Putaendo, reposici\u00f3n de retroexcavadora para Vi\u00f1a del Mar, reposici\u00f3n manipulador telesc\u00f3pico para Juan Fern\u00e1ndez, y la &nbsp;adquisici\u00f3n de cami\u00f3n bacheados para Quilpu\u00e9, entre otros.<\/p>\n\n\n\n<p>Junto a ello, se aprobaron relevantes iniciativas en el \u00e1mbito del cuidado del Medio Ambiente, como son el \u201cPrograma de potenciamiento en el uso de energ\u00edas renovables en hogares de las provincias de Quillota, Marga Marga, Los Andes, Petorca, y San Felipe\u201d, por M$346.500 de pesos.<\/p>\n\n\n\n<p>El <strong>Gobernador Regional de Valpara\u00edso, Rodrigo Mundaca, <\/strong>destac\u00f3 esta amplia aprobaci\u00f3n de proyectos, se\u00f1alando que \u201ceste cuerpo colegiado de consejeros y consejeras regionales, acaba de votar la continuidad del programa Pro Empleo para los pr\u00f3ximos 3 meses con una inversi\u00f3n de m\u00e1s de 3.200 millones de pesos, que es tremendamente importante y relevante (\u2026) &nbsp;Tambi\u00e9n hemos destinado m\u00e1s de 4.000 millones de pesos para el hospital de la Telet\u00f3n como gobierno regional y creo que eso habla muy bien de las y los consejeros regionales que est\u00e1n ac\u00e1\u201d.<\/p>\n\n\n\n<p>Junto a esto, la m\u00e1xima autoridad regional destac\u00f3 que \u201cEste es un trabajo de la mayor intensidad que hemos desarrollado con todos los consejeros regionales, y quiero darle much\u00edsimas gracias a todas y a todos por haber priorizado inversi\u00f3n en sectores que son estrat\u00e9gicos, en sectores que van a generar empleo porque los alcantarillados generan empleo, la reposici\u00f3n de los cuarteles de bomberos generan empleo, los proyectos de seguridad generan empleo, el hospital de la Telet\u00f3n genera empleo, que tambi\u00e9n para nosotros es tremendamente importante\u201d.<\/p>\n\n\n\n<p>Por su parte, e<strong>l consejero regional y presidente de la Comisi\u00f3n de Inversiones, Percy Mar\u00edn<\/strong>, recalc\u00f3 sobre el financiamiento al programa proempleo que \u201cHemos hablado con el Gobernador Regional y con el resto de los consejeros regionales y con los equipos t\u00e9cnicos para copiar una f\u00f3rmula que se lleva a cabo en la regi\u00f3n de O&#8217;Higgins, donde se hacen transferencias directas a los municipios y que, en definitiva, estos contratos dependan de los municipios, pero con fondos, naturalmente, del Gobierno Regional, ya no entregando estos recursos al Ministerio del Trabajo, ni tampoco entreg\u00e1ndoles la prerrogativa de la decisi\u00f3n de a qui\u00e9n o no contratar que tiene la delegaci\u00f3n presidencial\u201d.<\/p>\n\n\n\n<p>Finalmente, el <strong>consejero regional y presidente de la Comisi\u00f3n de Medio Ambiente, Eduardo Le\u00f3n<\/strong>, valor\u00f3 las iniciativas en este \u00e1mbito, concluyendo que \u201cLa crisis clim\u00e1tica est\u00e1 ac\u00e1, tenemos que enfrentarla, y hoy d\u00eda hemos aprobado dos programas muy concretos. El primero con la Serem\u00eda de Energ\u00eda sobre Educaci\u00f3n Ambiental para enfrentar la adaptaci\u00f3n al cambio clim\u00e1tico en m\u00e1s de 60 escuelas de la regi\u00f3n. Y otro, que lo hemos construido junto a la Serem\u00eda de Energ\u00eda y la SUDERE, que tiene que ver con la energ\u00eda solar distribuida. Este programa en 5 provincias, 24 comunas, van a haber 480 casas piloto, donde familias sencillas, humildes, van a poder acceder a paneles solares, y eso se va a ver reflejado en su boleta. Creo que son avances muy concretos que se hacen desde el Gobierno Regional\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; En pleno del Consejo Regional se aprob\u00f3 as\u00ed el financiamiento para 27 proyectos (FNDR) en la regi\u00f3n, en donde tambi\u00e9n destaca un aporte de m\u00e1s de 4 mil millones de pesos para nuevo centro Telet\u00f3n en Valpara\u00edso. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Una importante cartera de proyectos, priorizada por el Gobernador Regional Rodrigo Mundaca, fue aprobada en esta &hellip;<\/p>\n","protected":false},"author":2,"featured_media":3819,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[3],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2023\/12\/PROYECTOS-scaled.jpg","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/3818"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=3818"}],"version-history":[{"count":1,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/3818\/revisions"}],"predecessor-version":[{"id":3820,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/3818\/revisions\/3820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/3819"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=3818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=3818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=3818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}