{"id":3858,"date":"2023-12-21T02:42:32","date_gmt":"2023-12-21T02:42:32","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=3858"},"modified":"2023-12-21T02:42:34","modified_gmt":"2023-12-21T02:42:34","slug":"escuela-san-francisco-realizo-trabajo-en-conjunto-con-conaf-para-sensibilizar-y-preparar-a-las-comunidades-educativas-ante-incendios-forestales","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2023\/12\/21\/escuela-san-francisco-realizo-trabajo-en-conjunto-con-conaf-para-sensibilizar-y-preparar-a-las-comunidades-educativas-ante-incendios-forestales\/","title":{"rendered":"Escuela San Francisco realiz\u00f3 trabajo en conjunto con CONAF para sensibilizar y preparar a las comunidades educativas ante incendios forestales"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<ul><li>Esta iniciativa es parte del programa \u201cEscuelas Preparadas\u201d, que consiste en educar a las comunidades escolares sobre la importancia de la prevenci\u00f3n y el cuidado de los ecosistemas forestales, as\u00ed como de fomentar la seguridad y el conocimiento en situaciones de riesgo.<\/li><\/ul>\n\n\n\n<p>En el marco de la campa\u00f1a nacional \u201cEscuelas Preparadas Contra Incendios Forestales\u201d impulsada por la Corporaci\u00f3n Nacional Forestal (CONAF) y el Ministerio de Educaci\u00f3n (MINEDUC), profesionales de los organismos visitaron la Escuela San Francisco de San Esteban para trabajar en la sensibilizaci\u00f3n de los riesgos asociados al surgimiento de incendios, como tambi\u00e9n la de fomentar acciones de prevenci\u00f3n.<\/p>\n\n\n\n<p>Durante la jornada, se realizaron diversas actividades did\u00e1cticas y pr\u00e1cticas que involucraron a estudiantes, y docentes por parte de los profesionales de CONAF. Los participantes tuvieron la oportunidad de aprender sobre la prevenci\u00f3n de incendios y la identificaci\u00f3n de riesgos.<\/p>\n\n\n\n<p>Por su parte, el director de la Escuela San Francisco, Jos\u00e9 Escobar, se refiri\u00f3 a este trabajo conjunto que desarroll\u00f3 con CONAF, se\u00f1alando que \u201cme siento contento, como director de la Escuela San Francisco, el poder lograr conformar un equipo de estudiantes, la \u201cBrigada Ecol\u00f3gica Escolar\u201d en donde buscamos ser agentes de cambio y gestionamos acciones de educaci\u00f3n ambiental en el establecimiento, de una manera local. En base a la realidad del territorio, realizamos un diagn\u00f3stico medioambiental que fue apoyado por CONAF en el programa de \u201cEscuelas Preparadas frente a incendios forestales\u201d, donde los estudiantes comprendieron el impacto que podr\u00eda generar un incendio en nuestra escuela.<\/p>\n\n\n\n<p>Lamentablemente, nosotros nos encontramos muy alejados del centro de nuestra comuna, por lo que el tiempo de respuesta para responder ante un incendio en nuestro sector es fatal. Es por ello que como comunidad, se nos gener\u00f3 la necesidad de contar con elementos de protecci\u00f3n personal para cada uno de nuestros estudiantes en caso de alguna emergencia de la brigada. Esta adquisici\u00f3n la realizamos a trav\u00e9s del Plan de Mejoramiento Educativo (PME) bajo Ley SEP, para obviamente brindarle a los chicos y chicas de la protecci\u00f3n necesaria ante cualquier emergencia y potenciando el trabajo que desarrollaremos en el programa (Escuelas Preparadas) durante lo que queda de este a\u00f1o y el 2024.<\/p>\n\n\n\n<p>Precisamente, durante el a\u00f1o, el establecimiento educacional desarroll\u00f3 la iniciativa denominada \u201cBrigada Ecol\u00f3gica Escolar\u201d que tiene como objetivo trabajar y concientizar a la comunidad de San Francisco sobre los cuidados del territorio, en materias de no contaminaci\u00f3n en el territorio y sobre tener en cuenta las medidas en caso de una emergencia,&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta iniciativa es parte del programa \u201cEscuelas Preparadas\u201d, que consiste en educar a las comunidades escolares sobre la importancia de la prevenci\u00f3n y el cuidado de los ecosistemas forestales, as\u00ed como de fomentar la seguridad y el conocimiento en situaciones de riesgo. En el marco de la campa\u00f1a nacional \u201cEscuelas Preparadas Contra Incendios Forestales\u201d impulsada &hellip;<\/p>\n","protected":false},"author":2,"featured_media":3859,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[2],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2023\/12\/ESCUELA-SAN-FRANCISCO-CONAF-ESCUELAS-PREPARADAS-3.jpg","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/3858"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=3858"}],"version-history":[{"count":1,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/3858\/revisions"}],"predecessor-version":[{"id":3860,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/3858\/revisions\/3860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/3859"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=3858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=3858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=3858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}