{"id":4440,"date":"2024-08-23T04:03:56","date_gmt":"2024-08-23T04:03:56","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=4440"},"modified":"2024-08-23T04:03:58","modified_gmt":"2024-08-23T04:03:58","slug":"municipio-de-san-esteban-y-batalla-de-maestros-desarrollaran-el-primer-evento-de-improvisacion-masivo-de-la-comuna","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2024\/08\/23\/municipio-de-san-esteban-y-batalla-de-maestros-desarrollaran-el-primer-evento-de-improvisacion-masivo-de-la-comuna\/","title":{"rendered":"Municipio de San Esteban y \u201cBatalla de Maestros\u201d desarrollar\u00e1n el primer evento de improvisaci\u00f3n masivo de la comuna"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<ul><li>Este evento pionero se desarrollar\u00e1 el s\u00e1bado 24 de agosto y se realizar\u00e1 como cierre del mes de la juventud de la comuna.<\/li><\/ul>\n\n\n\n<p>Atenci\u00f3n a todas y todos los freestylers de Aconcagua, porque la reconocida \u201cBatalla de Maestros\u201d (BDM) llegar\u00e1 a San Esteban para realizar, en conjunto con el municipio, el primer evento de improvisaci\u00f3n de la comuna.<\/p>\n\n\n\n<p>Se trata del selectivo zonal BDM V Regi\u00f3n 2024, que permitir\u00e1 a los exponentes locales, participar y obtener uno de los cuatro cupos que estar\u00e1n disponibles para representar a San Esteban en la final del Torneo Regional Metropolitano BDM Chile.<\/p>\n\n\n\n<p>La iniciativa tiene como finalidad darle clausura al mes de la juventud, por lo que desde el municipio hacen una invitaci\u00f3n a todos los amantes del hip hop o que gusten de este tipo de competiciones, puedan asistir este s\u00e1bado 24 de agosto, desde las 14.00 horas, en el estadio municipal.<\/p>\n\n\n\n<p>Para el director de Desarrollo Comunitario, Exequiel Vald\u00e9s, esta actividad se da \u201cEn el contexto del d\u00eda de la juventud, por eso es que queremos invitar a todos nuestros vecinos y vecinas a la Batalla de Maestros. Un campeonato de freestyle, perteneciente a la rama del hip hop, que viene a innovar en la provincia. Queremos que muchos de nuestros j\u00f3venes puedan participar, o simplemente a escuchar estas competiciones, que de seguro estar\u00e1n de primer nivel\u00bb, afirm\u00f3.<\/p>\n\n\n\n<p>Las inscripciones iniciar\u00e1n desde las 14.00 hasta las 15.00 horas. Posteriormente comenzar\u00e1n las rondas de eliminaci\u00f3n.<\/p>\n\n\n\n<p>El evento estar\u00e1 comandado por el Maestro y Bufonk, quienes estar\u00e1n encendiendo la tarde y manejando las batallas. Los beatboxs estar\u00e1n a cargo de Beatbrotherss&nbsp; (adn 54 y S6xbitt), y como DJ, se presentar\u00e1 una de las grandes exponentes del Hip Hop chileno, DJ Reina Soul.<\/p>\n\n\n\n<p>El jurado estar\u00e1 compuesto por los reconocidos raperos: ADESONG, SATUL Y ELEMENTAL.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 es el \u201cfreestyle\u201d o improvisaci\u00f3n?<\/strong><\/p>\n\n\n\n<p>El freestyle rap o simplemente freestyle es la habilidad de rapear de forma improvisada sobre una base . A la persona que improvisa se le llama rapero, MC, freestyler, improvisador. Respecto a las batallas, implica una competici\u00f3n donde los participantes rivalizan con versos improvisados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este evento pionero se desarrollar\u00e1 el s\u00e1bado 24 de agosto y se realizar\u00e1 como cierre del mes de la juventud de la comuna. Atenci\u00f3n a todas y todos los freestylers de Aconcagua, porque la reconocida \u201cBatalla de Maestros\u201d (BDM) llegar\u00e1 a San Esteban para realizar, en conjunto con el municipio, el primer evento de improvisaci\u00f3n &hellip;<\/p>\n","protected":false},"author":2,"featured_media":4441,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[2],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2024\/08\/24-8-2024-SAN-ESTEBAN-2.png","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/4440"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=4440"}],"version-history":[{"count":1,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/4440\/revisions"}],"predecessor-version":[{"id":4442,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/4440\/revisions\/4442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/4441"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=4440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=4440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=4440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}