{"id":4775,"date":"2025-09-09T01:20:50","date_gmt":"2025-09-09T01:20:50","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=4775"},"modified":"2025-09-09T01:20:51","modified_gmt":"2025-09-09T01:20:51","slug":"el-club-de-atletismo-senior-de-los-andes-invita-a-campeonato-atletico-sabado-13-de-septiembre","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2025\/09\/09\/el-club-de-atletismo-senior-de-los-andes-invita-a-campeonato-atletico-sabado-13-de-septiembre\/","title":{"rendered":"EL CLUB DE ATLETISMO S\u00c9NIOR DE LOS ANDES INVITA A CAMPEONATO ATL\u00c9TICO, S\u00c1BADO 13 DE SEPTIEMBRE"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Se invita a participar del pr\u00f3ximo Campeonato de Atletismo S\u00e9nior que se realizar\u00e1 el este s\u00e1bado 13 de septiembre en el Estadio Regional de Los Andes.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"623\" src=\"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2025\/09\/e9bb94e5-a892-46cc-af77-e4544c700258-1024x623.jpg\" alt=\"\" data-id=\"4777\" data-full-url=\"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2025\/09\/e9bb94e5-a892-46cc-af77-e4544c700258.jpg\" data-link=\"https:\/\/lavozdesanesteban.cl\/?attachment_id=4777\" class=\"wp-image-4777\" srcset=\"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2025\/09\/e9bb94e5-a892-46cc-af77-e4544c700258-1024x623.jpg 1024w, https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2025\/09\/e9bb94e5-a892-46cc-af77-e4544c700258-300x183.jpg 300w, https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2025\/09\/e9bb94e5-a892-46cc-af77-e4544c700258-768x468.jpg 768w, https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2025\/09\/e9bb94e5-a892-46cc-af77-e4544c700258-1536x935.jpg 1536w, https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2025\/09\/e9bb94e5-a892-46cc-af77-e4544c700258.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Habr\u00e1 pruebas de lanzamientos de disco, bala y jabalina; y pruebas de pista de 100, 200, 400,1500 y 3000 metros planos.<\/p>\n\n\n\n<p>Pueden participar adultos desde los 35 a\u00f1os, damas y varones, previa inscripci\u00f3n al tel\u00e9fono +569 5396 4553.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2025\/09\/SEGUNDA-1024x768.jpg\" alt=\"\" data-id=\"4776\" data-full-url=\"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2025\/09\/SEGUNDA.jpg\" data-link=\"https:\/\/lavozdesanesteban.cl\/?attachment_id=4776\" class=\"wp-image-4776\" srcset=\"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2025\/09\/SEGUNDA-1024x768.jpg 1024w, https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2025\/09\/SEGUNDA-300x225.jpg 300w, https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2025\/09\/SEGUNDA-768x576.jpg 768w, https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2025\/09\/SEGUNDA-1536x1152.jpg 1536w, https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2025\/09\/SEGUNDA.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>El campeonato Atl\u00e9tico es organizado por el Club de Atletismo S\u00e9nior de Los Andes, miembro de FEMACHI, y desarrollar\u00e1 de 9 a 14 horas. La entrada de p\u00fablico es gratuita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se invita a participar del pr\u00f3ximo Campeonato de Atletismo S\u00e9nior que se realizar\u00e1 el este s\u00e1bado 13 de septiembre en el Estadio Regional de Los Andes. Habr\u00e1 pruebas de lanzamientos de disco, bala y jabalina; y pruebas de pista de 100, 200, 400,1500 y 3000 metros planos. Pueden participar adultos desde los 35 a\u00f1os, damas &hellip;<\/p>\n","protected":false},"author":2,"featured_media":4778,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[7],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2025\/09\/PRINCIPAL.jpg","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/4775"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=4775"}],"version-history":[{"count":1,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/4775\/revisions"}],"predecessor-version":[{"id":4779,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/4775\/revisions\/4779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/4778"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=4775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=4775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=4775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}