{"id":805,"date":"2022-04-17T01:38:11","date_gmt":"2022-04-17T01:38:11","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=805"},"modified":"2022-04-17T01:38:15","modified_gmt":"2022-04-17T01:38:15","slug":"como-identificar-senales-de-abuso-y-acoso-dentro-de-los-establecimientos-escolares","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2022\/04\/17\/como-identificar-senales-de-abuso-y-acoso-dentro-de-los-establecimientos-escolares\/","title":{"rendered":"\u00bfC\u00f3mo identificar se\u00f1ales de abuso y acoso dentro de los establecimientos escolares?"},"content":{"rendered":"\n<ul><li><strong>Producto de la preocupaci\u00f3n que han provocado los casos de violencia en las escuelas a nivel nacional, Daniela Palma, Trabajadora social de DAEM de San Esteban entrega recomendaci\u00f3n para reconocer y poder sobrellevar este problem\u00e1tica.<\/strong><\/li><\/ul>\n\n\n\n<p>Tras el retorno a clases presenciales se han viralizado en redes sociales y en los medios de comunicaci\u00f3n varios videos dando cuenta de un dr\u00e1stico aumento de violencia y acoso en los colegios a nivel nacional. Expertos han apuntado a las consecuencias del prolongado encierro producto de la pandemia, afectando a estudiantes a nivel emocional y psicol\u00f3gico, por lo que el retorno representa un proceso complejo de volver a socializar para muchos de ellos.<\/p>\n\n\n\n<p>En este marco, y en base a la campa\u00f1a iniciada por el municipio, titulada \u201cqueremos un San Esteban libre de bullying y discriminaci\u00f3n\u201d, es que la trabajadora social del Departamento de Educaci\u00f3n Municipal (DAEM), Daniela Palma, se\u00f1ala que los seres humanos somos sociales por naturaleza, dentro de una sociedad que nos interrelacionamos para aprender, desarrollar habilidades y autorrealizarnos, en rigor, todo el lapsus en que las ni\u00f1os y ni\u00f1os estuvieron encerrados, increment\u00f3 esta problem\u00e1tica: \u201cFueron dos a\u00f1os en donde los chicos no socializaron, donde existe un d\u00e9ficit en cuanto al logro de objetivos, a las relaciones interpersonales. Entonces, hay dos a\u00f1os en los que lamentablemente tenemos muchas consecuencias de ello\u201d, se\u00f1ala.<\/p>\n\n\n\n<p>En la misma l\u00ednea, la profesional agrega que \u201cEl bullying, desde mi mirada, es multicausal, es decir, que esto sucede debido a m\u00faltiples factores que influyen en la detonaci\u00f3n de una situaci\u00f3n de agresi\u00f3n. Podemos considerar la vinculaci\u00f3n que tienen las familias con la educaci\u00f3n de su hijo, qu\u00e9 tanto se comprometen en su ciclo educativo y que tanto la sociedad ha normalizado ciertas conductas de violencia como para lograr algunos beneficios\u201d.<\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo identificar estas acciones?<\/strong><\/p>\n\n\n\n<p>Seg\u00fan su experiencia, la profesional detalla que \u201cel bullying tiene ciertos \u201clineamientos\u201d como para poder detectarlo, uno de ellos es identificar que estas agresiones sean permanentes en el tiempo y no es una situaci\u00f3n aislada; debemos entender que el bullying es una acci\u00f3n de maltrato, ya sea violencia f\u00edsica y psicol\u00f3gica o eventualmente que se dan en las redes sociales, denominado ciber-bullying. Entonces, tenemos que tener a las comunidades educativas muy preparadas y pendientes de estas agresiones que no son aisladas, que no se dan en una sola ocasi\u00f3n\u201d.<\/p>\n\n\n\n<p>Por ello, es fundamental generar instancias para que los estudiantes puedan resolver sus conflictos: \u201cLa convivencia dentro del aula es muy importante, las personas que toman un rol fundamental son los profesores jefes, los profesores de asignatura quienes se vinculan y tienen este primer acercamiento con sus estudiantes, quienes pueden ir detectando si un grupo-curso por ejemplo, tiene una mala convivencia o les cuesta resolver conflictos o poseen poca comunicaci\u00f3n. Yo considero que eso podr\u00eda desencadenar alguna situaci\u00f3n de maltrato o quiz\u00e1s de conflicto entre pares\u201d.<\/p>\n\n\n\n<p><strong>Posibles Soluciones<\/strong><\/p>\n\n\n\n<p><a>Entre las soluciones que han abordado las autoridades, son la de fortalecer los programas de salud mental, tanto en profesores como en estudiantes, tambi\u00e9n se planea flexibilizar la jornada escolar completa y actividades de educaci\u00f3n no sexista.<\/a><\/p>\n\n\n\n<p>Por su parte, la trabajadora social de DAEM sugiere que para incentivar la resoluci\u00f3n pac\u00edfica de conflictos se\u00f1ala que \u201cse realizan en equipo, se llevan a cabo con las familias, la escuela y por supuesto que nosotros como instituci\u00f3n, como DAEM. Lo ideal es tener identificada estas situaciones y actuar de manera preventiva y no reactiva. La intenci\u00f3n es siempre educar y sensibilizar y crear espacios de poder entregar herramientas blandas, donde se les permita resolver e identificar los conflictos y juntos crear estrategias.\u201d<\/p>\n\n\n\n<p>\u201cCada escuela tienen distintas realidades, sin embargo, el bullying se da en todos los lugares y tendr\u00e1 las mismas caracter\u00edsticas. Por lo tanto, en conjunto con los apoderados y familias son quienes tienen un rol fundamental, el compromiso, la vinculaci\u00f3n que tengan y la sensibilizaci\u00f3n que tengan con estos temas son relevantes porque nosotros como comunidad educativa podemos crear estas instancias, sin embargo, si no contamos con el apoyo de los apoderados y desde la casa.\u201d &nbsp;Agrego Palma a esta materia.<\/p>\n\n\n\n<p>\u201cComo comunidad educativa hemos vivido situaciones dentro de la comuna, sin embargo, se han activado los protocolos, los cuales cada escuela tiene y en la misma l\u00ednea hemos trabajado en nuevas normas para prevenir otras situaciones, no de la l\u00ednea netamente del bullying, pero si con el fin de mejorar la convivencia escolar y de evitar estas posibles situaciones a futuro. Finalmente, este trabajo es mancomunado, es con las escuelas, actuando de una manera preventiva desde la educaci\u00f3n, desde estas instancias informativas, sensibilizadoras y de tal manera que la comunidad, la familia y el equipo DAEM se puedan movilizar en conjunto\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producto de la preocupaci\u00f3n que han provocado los casos de violencia en las escuelas a nivel nacional, Daniela Palma, Trabajadora social de DAEM de San Esteban entrega recomendaci\u00f3n para reconocer y poder sobrellevar este problem\u00e1tica. Tras el retorno a clases presenciales se han viralizado en redes sociales y en los medios de comunicaci\u00f3n varios videos &hellip;<\/p>\n","protected":false},"author":2,"featured_media":806,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[2],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2022\/04\/CONVIVENCI-A-1.jpeg","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/805"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=805"}],"version-history":[{"count":1,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/805\/revisions"}],"predecessor-version":[{"id":807,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/805\/revisions\/807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/806"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}