{"id":826,"date":"2022-04-17T02:23:31","date_gmt":"2022-04-17T02:23:31","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=826"},"modified":"2022-04-17T02:23:34","modified_gmt":"2022-04-17T02:23:34","slug":"cesfam-centenario-traslada-toma-de-pcr-desde-plaza-los-picapiedras-a-plaza-de-armas","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2022\/04\/17\/cesfam-centenario-traslada-toma-de-pcr-desde-plaza-los-picapiedras-a-plaza-de-armas\/","title":{"rendered":"Cesfam Centenario traslada toma de PCR desde Plaza Los Picapiedras a Plaza de Armas"},"content":{"rendered":"\n<p><em>Aumentar\u00e1n cupos a 180 muestras disponibles, de lunes a viernes<\/em><\/p>\n\n\n\n<p>A partir del lunes 18 de abril, los operativos de toma de PCR que el equipo de Cesfam Centenario desarrolla en la Plaza Los Picapiedras frente al recinto asistencial, se trasladan al centro de la ciudad en Plaza de Armas. Este ser\u00e1 el \u00fanico punto de testeo en la comuna.<\/p>\n\n\n\n<p>Francisco Ward, kinesi\u00f3logo encargado de B\u00fasqueda Activa de Cesfam Centenario, detall\u00f3 que en este punto fijo contin\u00faa el testeo a personas que no presenten s\u00edntomas COVID-19, de lunes a viernes de 09:00 a 12:00 horas, o hasta agotar el stock de 180 cupos diarios disponibles. El profesional agreg\u00f3 que los requisitos para acceder al examen PCR son no haber dado positivo a Coronavirus en los \u00faltimos dos meses y portar la c\u00e9dula de identidad.<\/p>\n\n\n\n<p>En cuanto al resultado de la muestra, Francisco Ward se\u00f1al\u00f3: \u201cdemora aproximadamente 24 horas, existe una aplicaci\u00f3n que se puede descargar en el tel\u00e9fono que es TriageApp, donde se ingresa con el rut y el n\u00famero de serie del carnet de identidad. Si no puede acceder, puede venir presencialmente a Cesfam o SAR y ac\u00e1 obtener su documentaci\u00f3n\u201d.&nbsp;<\/p>\n\n\n\n<p>Con relaci\u00f3n a la toma de test de ant\u00edgeno a personas que presentan sintomatolog\u00eda asociada a COVID-19, se est\u00e1 realizando testeo en horario de extensi\u00f3n en Cesfam Centenario, de lunes a jueves desde las 17:15, viernes desde las 16:15 y los s\u00e1bado o festivos desde las 08:15 en la ma\u00f1ana. Todo sujeto a la cantidad de cupos disponibles.<\/p>\n\n\n\n<p>Para mantenerse informados sobre los operativos de testeo que se realizan en la comuna, los interesados pueden seguir las redes sociales de Cesfam Centenario, en Facebook: Cesfam Centenario, Instagram: CesfamCentenario y Twitter: cesfcentenario; tambi\u00e9n a trav\u00e9s de las redes de la Municipalidad de Los Andes o del Servicio de Salud Aconcagua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aumentar\u00e1n cupos a 180 muestras disponibles, de lunes a viernes A partir del lunes 18 de abril, los operativos de toma de PCR que el equipo de Cesfam Centenario desarrolla en la Plaza Los Picapiedras frente al recinto asistencial, se trasladan al centro de la ciudad en Plaza de Armas. Este ser\u00e1 el \u00fanico punto &hellip;<\/p>\n","protected":false},"author":2,"featured_media":827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[7],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2022\/04\/CAMBIO-PCR-scaled.jpg","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/826"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=826"}],"version-history":[{"count":1,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/826\/revisions"}],"predecessor-version":[{"id":828,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/826\/revisions\/828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/827"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}