{"id":951,"date":"2022-04-26T23:05:38","date_gmt":"2022-04-26T23:05:38","guid":{"rendered":"https:\/\/lavozdesanesteban.cl\/?p=951"},"modified":"2022-04-26T23:05:41","modified_gmt":"2022-04-26T23:05:41","slug":"municipio-de-san-esteban-desarrollara-entretenida-corrida-y-cicletada-familiar-inclusiva-para-ir-en-apoyo-de-querida-deportista-local","status":"publish","type":"post","link":"https:\/\/lavozdesanesteban.cl\/index.php\/2022\/04\/26\/municipio-de-san-esteban-desarrollara-entretenida-corrida-y-cicletada-familiar-inclusiva-para-ir-en-apoyo-de-querida-deportista-local\/","title":{"rendered":"Municipio de San Esteban desarrollar\u00e1 entretenida corrida y cicletada familiar inclusiva para ir en apoyo de querida deportista local"},"content":{"rendered":"\n<ul><li>Como cierre del mes del deporte, la Municipalidad invita a todas y todos los vecinos de la comuna a asistir a este evento que permitir\u00e1 reunir fondos para adquirir una costosa silla de ruedas para Florencia Tapia, reconocida atleta paral\u00edmpica.<\/li><\/ul>\n\n\n\n<p>Este s\u00e1bado, la Municipalidad de San Esteban, a trav\u00e9s de su Oficina de Deportes, realizar\u00e1 una corrida y cicletada familiar inclusiva, que tiene como principal objetivo darle un cierre al exitoso mes del deporte y, a su vez, ir en apoyo de la destacada y querida deportista local paral\u00edmpica, Florencia Tapia, quien est\u00e1 reuniendo fondos para adquirir una costosa silla de ruedas para competir en los pr\u00f3ximos paral\u00edmpicos de este a\u00f1o.<\/p>\n\n\n\n<p>La iniciativa, que iniciar\u00e1 a las 17.00 horas en la Plaza de Armas de la comuna, no ser\u00e1 competitiva, y contar\u00e1 con una categor\u00eda, que se proyect\u00f3 en 5k.<\/p>\n\n\n\n<p>Marco Godoy, Encargado de la Oficina de Deportes, manifest\u00f3 que \u201cEn el marco del cierre del mes del deporte, es que desarrollaremos esta iniciativa que va en beneficio de nuestra destacada deportista que tenemos en la comuna, Florencia Tapia, que requiere comprarse una silla especial para participar en los pr\u00f3ximos paral\u00edmpicos. La idea es que todas y todos los vecinos puedan participar, ya que no ser\u00e1 competitivo, sino que tiene una ruta definida que ser\u00e1 de 5 kil\u00f3metros, para que participe todo el grupo familiar\u201d, sostuvo.<\/p>\n\n\n\n<p>Por su parte, Paulina Riquelme, Coordinadora Comunal del Programa de Integraci\u00f3n Escolar (PIE) de San Esteban, tambi\u00e9n se pleg\u00f3 a la invitaci\u00f3n, ya que \u201cnuestra intenci\u00f3n, es invitar a que todas y todos podamos participar como familia, sobre todo en las actividades de inclusi\u00f3n. Lo que queremos, en esta oportunidad, es poder apoyar a Florencia, pero no s\u00f3lo hacemos el llamado a las familias que pertenecen al PIE, sino tambi\u00e9n a todos los vecinos\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>Los interesados en participar, deber\u00e1n inscribirse a trav\u00e9s de la aplicaci\u00f3n m\u00f3vil gratuita que dispone el municipio, \u201cSan Esteban m\u00e1s cerca\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como cierre del mes del deporte, la Municipalidad invita a todas y todos los vecinos de la comuna a asistir a este evento que permitir\u00e1 reunir fondos para adquirir una costosa silla de ruedas para Florencia Tapia, reconocida atleta paral\u00edmpica. Este s\u00e1bado, la Municipalidad de San Esteban, a trav\u00e9s de su Oficina de Deportes, realizar\u00e1 &hellip;<\/p>\n","protected":false},"author":2,"featured_media":952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[2],"tags":[8],"jetpack_featured_media_url":"https:\/\/lavozdesanesteban.cl\/wp-content\/uploads\/2022\/04\/corrida-y-cicletada-inclusiva-familiar.jpg","_links":{"self":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/951"}],"collection":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/comments?post=951"}],"version-history":[{"count":1,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/951\/revisions"}],"predecessor-version":[{"id":953,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/posts\/951\/revisions\/953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media\/952"}],"wp:attachment":[{"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/media?parent=951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/categories?post=951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdesanesteban.cl\/index.php\/wp-json\/wp\/v2\/tags?post=951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}